{"id":26014,"date":"2024-02-13T14:37:58","date_gmt":"2024-02-13T12:37:58","guid":{"rendered":"https:\/\/shanky.staging24.link\/?post_type=product&#038;p=26014"},"modified":"2026-09-02T18:00:39","modified_gmt":"2026-09-02T15:00:39","slug":"%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4","status":"publish","type":"product","link":"https:\/\/www.shankysjudaica.com\/en\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/","title":{"rendered":"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2315536,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[536,535,454],"product_tag":[],"class_list":["post-26014","product","type-product","status-publish","has-post-thumbnail","product_cat-536","product_cat-535","product_cat-454","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shankysjudaica.com\/en\/product\/\u05e6\u05d9\u05e6\u05d9\u05ea-100-\u05db\u05d5\u05ea\u05e0\u05d4-\u05de\u05e1-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shankysjudaica.com\/en\/product\/\u05e6\u05d9\u05e6\u05d9\u05ea-100-\u05db\u05d5\u05ea\u05e0\u05d4-\u05de\u05e1-4\/\" \/>\n<meta property=\"og:site_name\" content=\"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T15:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2025\/03\/75068-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/\",\"url\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/\",\"name\":\"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shankysjudaica.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/75068.jpg\",\"datePublished\":\"2024-02-13T12:37:58+00:00\",\"dateModified\":\"2026-09-02T15:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.shankysjudaica.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/75068.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shankysjudaica.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/75068.jpg\",\"width\":228,\"height\":198},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/product\\\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shankysjudaica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.shankysjudaica.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#website\",\"url\":\"https:\\\/\\\/www.shankysjudaica.com\\\/\",\"name\":\"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\",\"description\":\"\u05de\u05d1\u05d7\u05e8 \u05e2\u05e0\u05e7 \u05e9\u05dc \u05e1\u05e4\u05e8\u05d9 \u05e7\u05d5\u05d3\u05e9 \u05d1\u05de\u05d7\u05d9\u05e8\u05d9\u05dd \u05d4\u05db\u05d9 \u05d8\u05d5\u05d1\u05d9\u05dd \u05e9\u05ea\u05de\u05e6\u05d0\u05d5\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shankysjudaica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#organization\",\"name\":\"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\",\"url\":\"https:\\\/\\\/www.shankysjudaica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shankysjudaica.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/shankisLogo.png\",\"contentUrl\":\"https:\\\/\\\/www.shankysjudaica.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/shankisLogo.png\",\"width\":193,\"height\":76,\"caption\":\"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shankysjudaica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shankysjudaica.com\/en\/product\/\u05e6\u05d9\u05e6\u05d9\u05ea-100-\u05db\u05d5\u05ea\u05e0\u05d4-\u05de\u05e1-4\/","og_locale":"en_US","og_type":"article","og_title":"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","og_url":"https:\/\/www.shankysjudaica.com\/en\/product\/\u05e6\u05d9\u05e6\u05d9\u05ea-100-\u05db\u05d5\u05ea\u05e0\u05d4-\u05de\u05e1-4\/","og_site_name":"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","article_modified_time":"2026-09-02T15:00:39+00:00","og_image":[{"width":228,"height":198,"url":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2025\/03\/75068-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/","url":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/","name":"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4 - \u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","isPartOf":{"@id":"https:\/\/www.shankysjudaica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/#primaryimage"},"image":{"@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2026\/08\/75068.jpg","datePublished":"2024-02-13T12:37:58+00:00","dateModified":"2026-09-02T15:00:39+00:00","breadcrumb":{"@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/#primaryimage","url":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2026\/08\/75068.jpg","contentUrl":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2026\/08\/75068.jpg","width":228,"height":198},{"@type":"BreadcrumbList","@id":"https:\/\/www.shankysjudaica.com\/product\/%d7%a6%d7%99%d7%a6%d7%99%d7%aa-100-%d7%9b%d7%95%d7%aa%d7%a0%d7%94-%d7%9e%d7%a1-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shankysjudaica.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.shankysjudaica.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u05e6\u05d9\u05e6\u05d9\u05ea 100% \u05db\u05d5\u05ea\u05e0\u05d4 \u05de\u05e1. 4"}]},{"@type":"WebSite","@id":"https:\/\/www.shankysjudaica.com\/#website","url":"https:\/\/www.shankysjudaica.com\/","name":"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","description":"\u05de\u05d1\u05d7\u05e8 \u05e2\u05e0\u05e7 \u05e9\u05dc \u05e1\u05e4\u05e8\u05d9 \u05e7\u05d5\u05d3\u05e9 \u05d1\u05de\u05d7\u05d9\u05e8\u05d9\u05dd \u05d4\u05db\u05d9 \u05d8\u05d5\u05d1\u05d9\u05dd \u05e9\u05ea\u05de\u05e6\u05d0\u05d5","publisher":{"@id":"https:\/\/www.shankysjudaica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shankysjudaica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.shankysjudaica.com\/#organization","name":"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s","url":"https:\/\/www.shankysjudaica.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.shankysjudaica.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2023\/11\/shankisLogo.png","contentUrl":"https:\/\/www.shankysjudaica.com\/wp-content\/uploads\/2023\/11\/shankisLogo.png","width":193,"height":76,"caption":"\u05e9\u05e0\u05e7\u05d9\u05e1 \u2022 Shanky&#039;s"},"image":{"@id":"https:\/\/www.shankysjudaica.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/product\/26014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/comments?post=26014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/media\/2315536"}],"wp:attachment":[{"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/media?parent=26014"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/product_brand?post=26014"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/product_cat?post=26014"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.shankysjudaica.com\/en\/wp-json\/wp\/v2\/product_tag?post=26014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}